{"id":858,"date":"2008-04-25T10:59:20","date_gmt":"2008-04-25T08:59:20","guid":{"rendered":"http:\/\/subaru.preproduccion.com\/blog\/wp-content\/2008\/04\/25\/subaru-posiblemente-la-mejor-traccion-del-mundo\/"},"modified":"2020-08-06T11:49:06","modified_gmt":"2020-08-06T09:49:06","slug":"subaru-posiblemente-la-mejor-traccion-del-mundo","status":"publish","type":"post","link":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/","title":{"rendered":"Subaru: posiblemente, la mejor tracci\u00f3n del mundo"},"content":{"rendered":"<p><center><object width=\"425\" height=\"355\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/Q7dVFY5CxT0&#038;hl=en\"><\/param><param name=\"wmode\" value=\"transparent\"><\/param><embed src=\"http:\/\/www.youtube.com\/v\/Q7dVFY5CxT0&#038;hl=en\" type=\"application\/x-shockwave-flash\" wmode=\"transparent\" width=\"425\" height=\"355\"><\/embed><\/object><\/center><\/p>\n<p>Espectacular v\u00eddeo que muestra claramente las diferencias entre el <strong>sistema AWD de Subaru<\/strong> y el resto de fabricantes. Durante 10 minutos de las m\u00e1s variadas pruebas se demuestra la superioridad de la tracci\u00f3n integral de Subaru en circunstancias extremas. <\/p>\n<p>Los <strong>Subaru Legacy<\/strong>, <strong>Outback <\/strong>y <strong>Tribeca <\/strong>completan recorridos de curvas cerradas en sucesi\u00f3n, cuesta arriba, sobre tierra o suelo mojado con una respuesta de conducci\u00f3n que casi es un homenaje a <strong>los ingenieros de Subaru<\/strong>. Frente a ellos, se puede comprobar la diferencia de comportamiento de otros autom\u00f3viles del mercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espectacular v\u00eddeo que muestra claramente las diferencias entre el sistema AWD de Subaru y el resto de fabricantes. Durante 10 minutos de las m\u00e1s variadas pruebas se demuestra la superioridad de la tracci\u00f3n integral de Subaru en circunstancias extremas. Los Subaru Legacy, Outback y Tribeca completan recorridos de curvas cerradas en sucesi\u00f3n, cuesta arriba, sobre [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","inline_featured_image":false,"footnotes":""},"categories":[4401],"tags":[17,537,538,4390,536],"class_list":["post-858","post","type-post","status-publish","format-standard","hentry","category-nuestra-marca","tag-awd","tag-la-mejor-traccion-del-mundo","tag-posiblemente","tag-subaru","tag-traccion-integral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subaru: posiblemente, la mejor tracci\u00f3n del mundo - Universo Subaru<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subaru: posiblemente, la mejor tracci\u00f3n del mundo - Universo Subaru\" \/>\n<meta property=\"og:description\" content=\"Espectacular v\u00eddeo que muestra claramente las diferencias entre el sistema AWD de Subaru y el resto de fabricantes. Durante 10 minutos de las m\u00e1s variadas pruebas se demuestra la superioridad de la tracci\u00f3n integral de Subaru en circunstancias extremas. Los Subaru Legacy, Outback y Tribeca completan recorridos de curvas cerradas en sucesi\u00f3n, cuesta arriba, sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Universo Subaru\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/subaruespana\" \/>\n<meta property=\"article:published_time\" content=\"2008-04-25T08:59:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-06T09:49:06+00:00\" \/>\n<meta name=\"author\" content=\"Subaru\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Subaru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/\"},\"author\":{\"name\":\"Subaru\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#\\\/schema\\\/person\\\/19a90b892230b8e0ec752704ddf4aa10\"},\"headline\":\"Subaru: posiblemente, la mejor tracci\u00f3n del mundo\",\"datePublished\":\"2008-04-25T08:59:20+00:00\",\"dateModified\":\"2020-08-06T09:49:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/\"},\"wordCount\":102,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#organization\"},\"keywords\":[\"awd\",\"la mejor tracci\u00f3n del mundo\",\"posiblemente\",\"Subaru\",\"tracci\u00f3n integral\"],\"articleSection\":[\"Nuestra marca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/\",\"url\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/\",\"name\":\"Subaru: posiblemente, la mejor tracci\u00f3n del mundo - Universo Subaru\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#website\"},\"datePublished\":\"2008-04-25T08:59:20+00:00\",\"dateModified\":\"2020-08-06T09:49:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/nuestra-marca\\\/subaru-posiblemente-la-mejor-traccion-del-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subaru: posiblemente, la mejor tracci\u00f3n del mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/\",\"name\":\"Universo Subaru\",\"description\":\"Descubre este apasionante espacio de Subaru donde vas a conocer todo sobre nuestros coches y las experiencias que vivimos con ellos. Si est\u00e1s preparado para dejarte seducir por la filosof\u00eda Subaru, qu\u00e9date con nosotros.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#organization\",\"name\":\"Subaru Espa\u00f1a S.A.\",\"url\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Logo-Subaru-TypeV_C300-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Logo-Subaru-TypeV_C300-scaled.jpg\",\"width\":2560,\"height\":1864,\"caption\":\"Subaru Espa\u00f1a S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/subaruespana\",\"https:\\\/\\\/www.instagram.com\\\/subarues\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/subaruespana\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/#\\\/schema\\\/person\\\/19a90b892230b8e0ec752704ddf4aa10\",\"name\":\"Subaru\",\"url\":\"https:\\\/\\\/www.subaru.es\\\/blog\\\/author\\\/subaria\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subaru: posiblemente, la mejor tracci\u00f3n del mundo - Universo Subaru","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/","og_locale":"es_ES","og_type":"article","og_title":"Subaru: posiblemente, la mejor tracci\u00f3n del mundo - Universo Subaru","og_description":"Espectacular v\u00eddeo que muestra claramente las diferencias entre el sistema AWD de Subaru y el resto de fabricantes. Durante 10 minutos de las m\u00e1s variadas pruebas se demuestra la superioridad de la tracci\u00f3n integral de Subaru en circunstancias extremas. Los Subaru Legacy, Outback y Tribeca completan recorridos de curvas cerradas en sucesi\u00f3n, cuesta arriba, sobre [&hellip;]","og_url":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/","og_site_name":"Universo Subaru","article_publisher":"https:\/\/www.facebook.com\/subaruespana","article_published_time":"2008-04-25T08:59:20+00:00","article_modified_time":"2020-08-06T09:49:06+00:00","author":"Subaru","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Subaru"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/#article","isPartOf":{"@id":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/"},"author":{"name":"Subaru","@id":"https:\/\/www.subaru.es\/blog\/#\/schema\/person\/19a90b892230b8e0ec752704ddf4aa10"},"headline":"Subaru: posiblemente, la mejor tracci\u00f3n del mundo","datePublished":"2008-04-25T08:59:20+00:00","dateModified":"2020-08-06T09:49:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/"},"wordCount":102,"commentCount":3,"publisher":{"@id":"https:\/\/www.subaru.es\/blog\/#organization"},"keywords":["awd","la mejor tracci\u00f3n del mundo","posiblemente","Subaru","tracci\u00f3n integral"],"articleSection":["Nuestra marca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/","url":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/","name":"Subaru: posiblemente, la mejor tracci\u00f3n del mundo - Universo Subaru","isPartOf":{"@id":"https:\/\/www.subaru.es\/blog\/#website"},"datePublished":"2008-04-25T08:59:20+00:00","dateModified":"2020-08-06T09:49:06+00:00","breadcrumb":{"@id":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.subaru.es\/blog\/nuestra-marca\/subaru-posiblemente-la-mejor-traccion-del-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.subaru.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Subaru: posiblemente, la mejor tracci\u00f3n del mundo"}]},{"@type":"WebSite","@id":"https:\/\/www.subaru.es\/blog\/#website","url":"https:\/\/www.subaru.es\/blog\/","name":"Universo Subaru","description":"Descubre este apasionante espacio de Subaru donde vas a conocer todo sobre nuestros coches y las experiencias que vivimos con ellos. Si est\u00e1s preparado para dejarte seducir por la filosof\u00eda Subaru, qu\u00e9date con nosotros.","publisher":{"@id":"https:\/\/www.subaru.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.subaru.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.subaru.es\/blog\/#organization","name":"Subaru Espa\u00f1a S.A.","url":"https:\/\/www.subaru.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.subaru.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.subaru.es\/blog\/wp-content\/uploads\/2016\/12\/Logo-Subaru-TypeV_C300-scaled.jpg","contentUrl":"https:\/\/www.subaru.es\/blog\/wp-content\/uploads\/2016\/12\/Logo-Subaru-TypeV_C300-scaled.jpg","width":2560,"height":1864,"caption":"Subaru Espa\u00f1a S.A."},"image":{"@id":"https:\/\/www.subaru.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/subaruespana","https:\/\/www.instagram.com\/subarues\/","https:\/\/www.youtube.com\/user\/subaruespana"]},{"@type":"Person","@id":"https:\/\/www.subaru.es\/blog\/#\/schema\/person\/19a90b892230b8e0ec752704ddf4aa10","name":"Subaru","url":"https:\/\/www.subaru.es\/blog\/author\/subaria\/"}]}},"_links":{"self":[{"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/posts\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":1,"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/posts\/858\/revisions"}],"predecessor-version":[{"id":15585,"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/posts\/858\/revisions\/15585"}],"wp:attachment":[{"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/categories?post=858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.subaru.es\/blog\/wp-json\/wp\/v2\/tags?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}